{"id":245,"count":8,"description":"","link":"https:\/\/kombi-line.com\/index\/product-category\/poklopac-rezervoara-peugot-boxer-06-24\/","name":"Poklopac rezervoara PEUGOT BOXER 06-24","slug":"poklopac-rezervoara-peugot-boxer-06-24","taxonomy":"product_cat","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Poklopac rezervoara PEUGOT BOXER 06-24 Archives - Kombi Line - Dijelovi za kombi vozila<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kombi-line.com\/index\/product-category\/poklopac-rezervoara-peugot-boxer-06-24\/\" \/>\n<meta property=\"og:locale\" content=\"bs_BA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Poklopac rezervoara PEUGOT BOXER 06-24 Archives - Kombi Line - Dijelovi za kombi vozila\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kombi-line.com\/index\/product-category\/poklopac-rezervoara-peugot-boxer-06-24\/\" \/>\n<meta property=\"og:site_name\" content=\"Kombi Line - Dijelovi za kombi vozila\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/kombi-line.com\/index\/product-category\/poklopac-rezervoara-peugot-boxer-06-24\/\",\"url\":\"https:\/\/kombi-line.com\/index\/product-category\/poklopac-rezervoara-peugot-boxer-06-24\/\",\"name\":\"Poklopac rezervoara PEUGOT BOXER 06-24 Archives - Kombi Line - Dijelovi za kombi vozila\",\"isPartOf\":{\"@id\":\"https:\/\/kombi-line.com\/index\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/kombi-line.com\/index\/product-category\/poklopac-rezervoara-peugot-boxer-06-24\/#breadcrumb\"},\"inLanguage\":\"bs-BA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/kombi-line.com\/index\/product-category\/poklopac-rezervoara-peugot-boxer-06-24\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/kombi-line.com\/index\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Poklopac rezervoara PEUGOT BOXER 06-24\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/kombi-line.com\/index\/#website\",\"url\":\"https:\/\/kombi-line.com\/index\/\",\"name\":\"Kombi Line - Dijelovi za kombi vozila\",\"description\":\"Dijelovi i oprema za kombije\",\"publisher\":{\"@id\":\"https:\/\/kombi-line.com\/index\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/kombi-line.com\/index\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"bs-BA\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/kombi-line.com\/index\/#organization\",\"name\":\"Kombi Line - Dijelovi za kombi vozila\",\"url\":\"https:\/\/kombi-line.com\/index\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"bs-BA\",\"@id\":\"https:\/\/kombi-line.com\/index\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/kombi-line.com\/index\/wp-content\/uploads\/2024\/10\/cropped-OLX.ba6927976512362549476-07d57e8a1959-removebg-preview.png\",\"contentUrl\":\"https:\/\/kombi-line.com\/index\/wp-content\/uploads\/2024\/10\/cropped-OLX.ba6927976512362549476-07d57e8a1959-removebg-preview.png\",\"width\":315,\"height\":164,\"caption\":\"Kombi Line - Dijelovi za kombi vozila\"},\"image\":{\"@id\":\"https:\/\/kombi-line.com\/index\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Poklopac rezervoara PEUGOT BOXER 06-24 Archives - Kombi Line - Dijelovi za kombi vozila","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kombi-line.com\/index\/product-category\/poklopac-rezervoara-peugot-boxer-06-24\/","og_locale":"bs_BA","og_type":"article","og_title":"Poklopac rezervoara PEUGOT BOXER 06-24 Archives - Kombi Line - Dijelovi za kombi vozila","og_url":"https:\/\/kombi-line.com\/index\/product-category\/poklopac-rezervoara-peugot-boxer-06-24\/","og_site_name":"Kombi Line - Dijelovi za kombi vozila","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/kombi-line.com\/index\/product-category\/poklopac-rezervoara-peugot-boxer-06-24\/","url":"https:\/\/kombi-line.com\/index\/product-category\/poklopac-rezervoara-peugot-boxer-06-24\/","name":"Poklopac rezervoara PEUGOT BOXER 06-24 Archives - Kombi Line - Dijelovi za kombi vozila","isPartOf":{"@id":"https:\/\/kombi-line.com\/index\/#website"},"breadcrumb":{"@id":"https:\/\/kombi-line.com\/index\/product-category\/poklopac-rezervoara-peugot-boxer-06-24\/#breadcrumb"},"inLanguage":"bs-BA"},{"@type":"BreadcrumbList","@id":"https:\/\/kombi-line.com\/index\/product-category\/poklopac-rezervoara-peugot-boxer-06-24\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kombi-line.com\/index\/"},{"@type":"ListItem","position":2,"name":"Poklopac rezervoara PEUGOT BOXER 06-24"}]},{"@type":"WebSite","@id":"https:\/\/kombi-line.com\/index\/#website","url":"https:\/\/kombi-line.com\/index\/","name":"Kombi Line - Dijelovi za kombi vozila","description":"Dijelovi i oprema za kombije","publisher":{"@id":"https:\/\/kombi-line.com\/index\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kombi-line.com\/index\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"bs-BA"},{"@type":"Organization","@id":"https:\/\/kombi-line.com\/index\/#organization","name":"Kombi Line - Dijelovi za kombi vozila","url":"https:\/\/kombi-line.com\/index\/","logo":{"@type":"ImageObject","inLanguage":"bs-BA","@id":"https:\/\/kombi-line.com\/index\/#\/schema\/logo\/image\/","url":"https:\/\/kombi-line.com\/index\/wp-content\/uploads\/2024\/10\/cropped-OLX.ba6927976512362549476-07d57e8a1959-removebg-preview.png","contentUrl":"https:\/\/kombi-line.com\/index\/wp-content\/uploads\/2024\/10\/cropped-OLX.ba6927976512362549476-07d57e8a1959-removebg-preview.png","width":315,"height":164,"caption":"Kombi Line - Dijelovi za kombi vozila"},"image":{"@id":"https:\/\/kombi-line.com\/index\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/kombi-line.com\/index\/wp-json\/wp\/v2\/product_cat\/245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kombi-line.com\/index\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/kombi-line.com\/index\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/kombi-line.com\/index\/wp-json\/wp\/v2\/product?product_cat=245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}